{"id":2497,"date":"2016-07-28T09:14:41","date_gmt":"2016-07-28T08:14:41","guid":{"rendered":"http:\/\/influenceassociates.com\/?p=2497"},"modified":"2016-07-28T09:14:41","modified_gmt":"2016-07-28T08:14:41","slug":"vuhl-inaugura-un-nuevo-showroom-company-hq-ciudad-de-mexico","status":"publish","type":"post","link":"https:\/\/influenceassociates.com\/es\/vuhl-opens-new-showroom-company-hq-mexico-city\/","title":{"rendered":"VUHL inaugura una nueva sala de exposiciones y la sede de la empresa en Ciudad de M\u00e9xico"},"content":{"rendered":"<ul>\n<li>Ya se han vendido los tres modelos presentados en la inauguraci\u00f3n<\/li>\n<li>Entre los invitados VIP figuran representantes del Gobierno mexicano, la Secretar\u00eda de Econom\u00eda, el piloto de carreras Guillermo Rojas Senior, Surman Group<\/li>\n<li>Sigue a los acuerdos de distribuci\u00f3n internacional en el Reino Unido y Oriente Medio establecidos en 2015<\/li>\n<\/ul>\n<p><a href=\"http:\/\/vuhl05.com\/\" target=\"_blank\">VUHL<\/a>El fabricante mexicano de superdeportivos ligeros, fundado en 2010, celebra su a\u00f1o m\u00e1s exitoso hasta la fecha con la apertura de una nueva sala de exposiciones en el elegante barrio de Polanco, en Ciudad de M\u00e9xico.<\/p>\n<p>La nueva sala de exposici\u00f3n de VUHL forma parte de las instalaciones del Grupo Surman en los Campos El\u00edseos de Polanco (Ciudad de M\u00e9xico) y est\u00e1 situada entre otras marcas del Grupo, como Bentley y Ducati.  Surman es uno de los mayores distribuidores de autom\u00f3viles de M\u00e9xico, establecido desde hace m\u00e1s de 30 a\u00f1os, con unas 80 salas de exposici\u00f3n que representan marcas como Audi, Bentley, Ducati, Porsche y ahora VUHL.<\/p>\n<p>Poco despu\u00e9s de que los coches VUHL salieran a la venta por primera vez en el Reino Unido con <a href=\"\/es\/www.bespokeperformance.co.uk\/\" target=\"_blank\">Rendimiento a medida<\/a> y el debut mundial del nuevo VUHL 05RR de 600 CV por tonelada en el Sal\u00f3n de este a\u00f1o. <a href=\"https:\/\/www.goodwood.com\/flagship-events\/festival-of-speed\/\" target=\"_blank\">Festival de Velocidad de Goodwood<\/a>2016 es el a\u00f1o de mayor \u00e9xito de la empresa hasta la fecha, con todos los veh\u00edculos expuestos en la nueva sala de exposiciones de Ciudad de M\u00e9xico ya vendidos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-2501\" src=\"https:\/\/influenceassociates.com\/wordpress-cms\/wp-content\/uploads\/2016\/07\/MG_9524-339x339.jpeg\" alt=\"NO.\" width=\"339\" height=\"339\" srcset=\"https:\/\/influenceassociates.com\/wordpress-cms\/wp-content\/uploads\/2016\/07\/MG_9524-339x339.jpeg 339w, https:\/\/influenceassociates.com\/wordpress-cms\/wp-content\/uploads\/2016\/07\/MG_9524-150x150.jpeg 150w, https:\/\/influenceassociates.com\/wordpress-cms\/wp-content\/uploads\/2016\/07\/MG_9524-356x356.jpeg 356w, https:\/\/influenceassociates.com\/wordpress-cms\/wp-content\/uploads\/2016\/07\/MG_9524-148x148.jpeg 148w\" sizes=\"auto, (max-width: 339px) 100vw, 339px\" \/><\/p>\n<p>Un centenar de invitados, entre nuevos clientes y personalidades, asistieron a la inauguraci\u00f3n de la nueva sala de exposiciones, dise\u00f1ada conjuntamente por el director t\u00e9cnico de VUHL, Iker Echeverr\u00eda, y el arquitecto Alejandro Esparza.<\/p>\n<p>Guillermo Echeverr\u00eda, cofundador de VUHL, ha declarado: \"Este es un a\u00f1o muy especial para VUHL, nos sentimos debidamente establecidos en 2016, con un buen n\u00famero de coches vendidos, nuevos socios de distribuci\u00f3n en el Reino Unido y Oriente Medio y el lanzamiento de nuestra \u00faltima 05RR.  Nuestro nuevo showroom aqu\u00ed en nuestra ciudad natal literalmente cimenta nuestro negocio como un orgulloso producto mexicano con una visi\u00f3n global - planeamos emular este dise\u00f1o y sensaci\u00f3n en nuestros otros mercados clave alrededor del mundo.\"<\/p>\n<p>La nueva sala de exposici\u00f3n de dos plantas cuenta con tres coches nuevos, una estructura monocasco (s\u00f3lo 78 kg) para demostrar la base superligera del veh\u00edculo, m\u00e1s componentes ligeros con el expositor de llantas de carbono a medida de VUHL, mercanc\u00eda exclusiva, mientras que en la planta superior hay un configurador exclusivo de VUHL y un servicio de reserva de pruebas de conducci\u00f3n.<\/p>","protected":false},"excerpt":{"rendered":"<p>Tres modelos mostrados en la noche de apertura ya vendidos Invitados VIP incluyendo representantes del Gobierno Mexicano, Secretar\u00eda de Econom\u00eda, piloto de carreras Guillermo Rojas Senior, Surman Group Sigue a las asociaciones internacionales de distribuci\u00f3n en el Reino Unido y Oriente Medio establecidas en 2015....<\/p>","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2497","post","type-post","status-publish","format-standard","hentry","category-uncategorised"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VUHL Opens New Showroom and Company HQ in Mexico City - Influence Associates<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/influenceassociates.com\/es\/vuhl-inaugura-un-nuevo-showroom-company-hq-ciudad-de-mexico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VUHL Opens New Showroom and Company HQ in Mexico City - Influence Associates\" \/>\n<meta property=\"og:description\" content=\"Three models shown on opening night already sold VIP guests including Mexican Government representatives, Economy Secretariat, racing driver Guillermo Rojas Senior, Surman Group Follows international distribution partnerships in the UK and Middle East established in 2015&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/influenceassociates.com\/es\/vuhl-inaugura-un-nuevo-showroom-company-hq-ciudad-de-mexico\/\" \/>\n<meta property=\"og:site_name\" content=\"Influence Associates\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-28T08:14:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/influenceassociates.com\/wordpress-cms\/wp-content\/uploads\/2016\/07\/MG_9524-339x339.jpeg\" \/>\n<meta name=\"author\" content=\"Influence iNews Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@InfluenceComms\" \/>\n<meta name=\"twitter:site\" content=\"@InfluenceComms\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Influence iNews Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/vuhl-opens-new-showroom-company-hq-mexico-city\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/vuhl-opens-new-showroom-company-hq-mexico-city\\\/\"},\"author\":{\"name\":\"Influence iNews Team\",\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/#\\\/schema\\\/person\\\/12578eb426032924a60797cb1629f68b\"},\"headline\":\"VUHL Opens New Showroom and Company HQ in Mexico City\",\"datePublished\":\"2016-07-28T08:14:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/vuhl-opens-new-showroom-company-hq-mexico-city\\\/\"},\"wordCount\":345,\"image\":{\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/vuhl-opens-new-showroom-company-hq-mexico-city\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/influenceassociates.com\\\/wordpress-cms\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/MG_9524-339x339.jpeg\",\"articleSection\":[\"Uncategorised\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/vuhl-opens-new-showroom-company-hq-mexico-city\\\/\",\"url\":\"https:\\\/\\\/influenceassociates.com\\\/vuhl-opens-new-showroom-company-hq-mexico-city\\\/\",\"name\":\"VUHL Opens New Showroom and Company HQ in Mexico City - Influence Associates\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/vuhl-opens-new-showroom-company-hq-mexico-city\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/vuhl-opens-new-showroom-company-hq-mexico-city\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/influenceassociates.com\\\/wordpress-cms\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/MG_9524-339x339.jpeg\",\"datePublished\":\"2016-07-28T08:14:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/#\\\/schema\\\/person\\\/12578eb426032924a60797cb1629f68b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/vuhl-opens-new-showroom-company-hq-mexico-city\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/influenceassociates.com\\\/vuhl-opens-new-showroom-company-hq-mexico-city\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/vuhl-opens-new-showroom-company-hq-mexico-city\\\/#primaryimage\",\"url\":\"https:\\\/\\\/influenceassociates.com\\\/wordpress-cms\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/MG_9524-339x339.jpeg\",\"contentUrl\":\"https:\\\/\\\/influenceassociates.com\\\/wordpress-cms\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/MG_9524-339x339.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/vuhl-opens-new-showroom-company-hq-mexico-city\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/influenceassociates.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VUHL Opens New Showroom and Company HQ in Mexico City\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/#website\",\"url\":\"https:\\\/\\\/influenceassociates.com\\\/\",\"name\":\"Influence Associates\",\"description\":\"Communications &amp; PR, Brand Strategy and Reputation Management\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/influenceassociates.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/#\\\/schema\\\/person\\\/12578eb426032924a60797cb1629f68b\",\"name\":\"Influence iNews Team\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VUHL abre una nueva sala de exposici\u00f3n y sede de la empresa en Ciudad de M\u00e9xico - Influence Associates","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/influenceassociates.com\/es\/vuhl-inaugura-un-nuevo-showroom-company-hq-ciudad-de-mexico\/","og_locale":"es_ES","og_type":"article","og_title":"VUHL Opens New Showroom and Company HQ in Mexico City - Influence Associates","og_description":"Three models shown on opening night already sold VIP guests including Mexican Government representatives, Economy Secretariat, racing driver Guillermo Rojas Senior, Surman Group Follows international distribution partnerships in the UK and Middle East established in 2015&hellip;","og_url":"https:\/\/influenceassociates.com\/es\/vuhl-inaugura-un-nuevo-showroom-company-hq-ciudad-de-mexico\/","og_site_name":"Influence Associates","article_published_time":"2016-07-28T08:14:41+00:00","og_image":[{"url":"https:\/\/influenceassociates.com\/wordpress-cms\/wp-content\/uploads\/2016\/07\/MG_9524-339x339.jpeg","type":"","width":"","height":""}],"author":"Influence iNews Team","twitter_card":"summary_large_image","twitter_creator":"@InfluenceComms","twitter_site":"@InfluenceComms","twitter_misc":{"Escrito por":"Influence iNews Team","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/influenceassociates.com\/vuhl-opens-new-showroom-company-hq-mexico-city\/#article","isPartOf":{"@id":"https:\/\/influenceassociates.com\/vuhl-opens-new-showroom-company-hq-mexico-city\/"},"author":{"name":"Influence iNews Team","@id":"https:\/\/influenceassociates.com\/#\/schema\/person\/12578eb426032924a60797cb1629f68b"},"headline":"VUHL Opens New Showroom and Company HQ in Mexico City","datePublished":"2016-07-28T08:14:41+00:00","mainEntityOfPage":{"@id":"https:\/\/influenceassociates.com\/vuhl-opens-new-showroom-company-hq-mexico-city\/"},"wordCount":345,"image":{"@id":"https:\/\/influenceassociates.com\/vuhl-opens-new-showroom-company-hq-mexico-city\/#primaryimage"},"thumbnailUrl":"https:\/\/influenceassociates.com\/wordpress-cms\/wp-content\/uploads\/2016\/07\/MG_9524-339x339.jpeg","articleSection":["Uncategorised"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/influenceassociates.com\/vuhl-opens-new-showroom-company-hq-mexico-city\/","url":"https:\/\/influenceassociates.com\/vuhl-opens-new-showroom-company-hq-mexico-city\/","name":"VUHL abre una nueva sala de exposici\u00f3n y sede de la empresa en Ciudad de M\u00e9xico - Influence Associates","isPartOf":{"@id":"https:\/\/influenceassociates.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/influenceassociates.com\/vuhl-opens-new-showroom-company-hq-mexico-city\/#primaryimage"},"image":{"@id":"https:\/\/influenceassociates.com\/vuhl-opens-new-showroom-company-hq-mexico-city\/#primaryimage"},"thumbnailUrl":"https:\/\/influenceassociates.com\/wordpress-cms\/wp-content\/uploads\/2016\/07\/MG_9524-339x339.jpeg","datePublished":"2016-07-28T08:14:41+00:00","author":{"@id":"https:\/\/influenceassociates.com\/#\/schema\/person\/12578eb426032924a60797cb1629f68b"},"breadcrumb":{"@id":"https:\/\/influenceassociates.com\/vuhl-opens-new-showroom-company-hq-mexico-city\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/influenceassociates.com\/vuhl-opens-new-showroom-company-hq-mexico-city\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/influenceassociates.com\/vuhl-opens-new-showroom-company-hq-mexico-city\/#primaryimage","url":"https:\/\/influenceassociates.com\/wordpress-cms\/wp-content\/uploads\/2016\/07\/MG_9524-339x339.jpeg","contentUrl":"https:\/\/influenceassociates.com\/wordpress-cms\/wp-content\/uploads\/2016\/07\/MG_9524-339x339.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/influenceassociates.com\/vuhl-opens-new-showroom-company-hq-mexico-city\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/influenceassociates.com\/"},{"@type":"ListItem","position":2,"name":"VUHL Opens New Showroom and Company HQ in Mexico City"}]},{"@type":"WebSite","@id":"https:\/\/influenceassociates.com\/#website","url":"https:\/\/influenceassociates.com\/","name":"Asociados de influencia","description":"Comunicaci\u00f3n y relaciones p\u00fablicas, estrategia de marca y gesti\u00f3n de la reputaci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/influenceassociates.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/influenceassociates.com\/#\/schema\/person\/12578eb426032924a60797cb1629f68b","name":"Influencia Equipo iNews"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/influenceassociates.com\/es\/wp-json\/wp\/v2\/posts\/2497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influenceassociates.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influenceassociates.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influenceassociates.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/influenceassociates.com\/es\/wp-json\/wp\/v2\/comments?post=2497"}],"version-history":[{"count":0,"href":"https:\/\/influenceassociates.com\/es\/wp-json\/wp\/v2\/posts\/2497\/revisions"}],"wp:attachment":[{"href":"https:\/\/influenceassociates.com\/es\/wp-json\/wp\/v2\/media?parent=2497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influenceassociates.com\/es\/wp-json\/wp\/v2\/categories?post=2497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influenceassociates.com\/es\/wp-json\/wp\/v2\/tags?post=2497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}