{"id":1024,"date":"2016-01-16T14:44:55","date_gmt":"2016-01-16T14:44:55","guid":{"rendered":"https:\/\/influenceassociates.com\/wordpress-cms\/?p=1024"},"modified":"2016-05-06T15:30:29","modified_gmt":"2016-05-06T14:30:29","slug":"1024-2","status":"publish","type":"post","link":"https:\/\/influenceassociates.com\/fr\/1024-2\/","title":{"rendered":"Damon Hill OBE \u00e0 Autosport International"},"content":{"rendered":"<p>Relations publiques de l'\u00e9v\u00e9nement :<\/p>\n<ul>\n<li>Damon Hill OBE a ouvert <em>Autosport International<\/em> aujourd'hui et sera la vedette de l'exposition de ce week-end.<\/li>\n<li>Hill c\u00e9l\u00e8bre le 20e anniversaire de la cr\u00e9ation de l'entreprise.<sup>th<\/sup> anniversaire de sa victoire au championnat du monde de F1 en 1996 au NEC.<\/li>\n<li>Plus t\u00f4t dans la matin\u00e9e, il a retrouv\u00e9 sa voiture de course Williams-Renault FW18, qui lui a permis de remporter le championnat.<\/li>\n<li>Le champion du monde de F1 de 1996 appara\u00eetra sur le site de l'Union europ\u00e9enne. <em>Autosport<\/em> Stage tout au long du week-end et participera \u00e0 plusieurs s\u00e9ances d'autographes.<\/li>\n<li><em>Autosport International<\/em> se d\u00e9roule jusqu'au 17 janvier*. Les billets sont encore disponibles aupr\u00e8s de<a href=\"http:\/\/www.autosportinternational.com\/\">www.autosportinternational.com<\/a><\/li>\n<\/ul>\n<p><em>Samedi 16<sup>th<\/sup> Janvier \u00a0\u00a0<\/em><\/p>\n<p>Damon Hill OBE est la star de <em>Autosport International<\/em> ce week-end, o\u00f9 il c\u00e9l\u00e8bre le 20e anniversaire de sa naissance.<sup>th<\/sup>anniversaire de sa victoire au championnat du monde de F1 en 1996 avec des milliers de fans au NEC.<\/p>\n<p>Hill, qui se produira \u00e0 <em>Autosport International<\/em> aujourd'hui et dimanche 17<sup>th<\/sup> janvier, a inaugur\u00e9 l'\u00e9v\u00e9nement du NEC ce matin avec Petter Solberg, qui a coup\u00e9 le ruban devant de nombreux fans de sport automobile enthousiastes.<\/p>\n<p>Il a retrouv\u00e9 sa voiture de course Williams FW18 sur le stand Williams, celle qui l'a conduit \u00e0 la victoire en 1996 et qui est l'une des voitures de F1 les plus performantes de l'histoire. Hill appara\u00eetra sur le stand de Williams. <em>Autosport<\/em> au cours des journ\u00e9es de samedi et dimanche, et participera \u00e0 plusieurs s\u00e9ances de signatures d'autographes.<\/p>\n<p>L'un des pilotes de course britanniques les plus appr\u00e9ci\u00e9s de tous les temps, Hill a obtenu son premier si\u00e8ge en Formule 1 avec Brabham en 1992, mais c'est avec Williams qu'il est le plus associ\u00e9, et ce gr\u00e2ce \u00e0 une caract\u00e9ristique unique de c\u00e9l\u00e9bration de Williams,<em>Autosport International\u00a0<\/em>permettra \u00e0 Hill de retrouver non seulement sa voiture championne, mais aussi certains membres cl\u00e9s de l'\u00e9quipe Williams.<\/p>\n<p>Apr\u00e8s avoir effectu\u00e9 des essais pour la c\u00e9l\u00e8bre \u00e9curie de Sir Frank Williams en 1991, Hill a obtenu une place de pilote en 1993, aux c\u00f4t\u00e9s d'Alain Prost, avant d'\u00eatre le partenaire d'Ayrton Senna en 1994, ann\u00e9e fatidique au cours de laquelle le Br\u00e9silien a perdu la vie lors du Grand Prix de Saint-Marin.<\/p>\n<p>Les luttes entre Hill et Michael Schumacher au cours de cette m\u00eame saison sont entr\u00e9es dans la l\u00e9gende - notamment le tristement c\u00e9l\u00e8bre accident d'Ad\u00e9la\u00efde, qui l'a priv\u00e9 du titre pour un seul point - mais tout s'est jou\u00e9 en 1996, lorsque Hill est devenu champion du monde lors du Grand Prix du Japon.<\/p>\n<p>Cette saison-l\u00e0, la Williams-Renault FW18 a remport\u00e9 12 victoires en 16 courses (huit dans les mains de Hill, quatre dans celles de son co\u00e9quipier Jacques Villeneuve) et est statistiquement la voiture de Formule 1 Williams la plus performante de tous les temps, avec 175 points marqu\u00e9s - le plus grand nombre de points marqu\u00e9s en une saison selon l'ancien syst\u00e8me de notation.<\/p>\n<p>Visiteurs de <em>Autosport International<\/em> pourront voir de pr\u00e8s la FW18, ainsi qu'une multitude d'autres voitures de F1 Williams des quatre derni\u00e8res d\u00e9cennies. Parmi une multitude d'expositions in\u00e9dites, le point central sera une sc\u00e8ne Autosport r\u00e9am\u00e9nag\u00e9e qui accueillera le motorhome Williams Martini Racing de huit m\u00e8tres de haut construit juste \u00e0 c\u00f4t\u00e9 - c'est la premi\u00e8re fois qu'il est \u00e9rig\u00e9 en dehors d'un circuit de course automobile.<\/p>\n<p>Billets pour <em>Autosport International<\/em> sont encore disponibles, rendez-vous sur le site <a href=\"http:\/\/www.autosportinternational.com\/\">www.autosportinternational.com<\/a>.<\/p>\n<p><em>Laura Simpson<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Influence Associates a \u00e9t\u00e9 cr\u00e9\u00e9e pour \u00eatre la meilleure agence de relations publiques dans le domaine de l'automobile, du sport automobile et des voitures de collection au monde. Avec l'\u00e9quipe de direction la plus exp\u00e9riment\u00e9e du secteur des relations publiques automobiles, nous sommes parfaitement plac\u00e9s pour fournir un service de premier ordre \u00e0 notre portefeuille de clients de premier ordre.<\/p>\n<p>Nous sommes des cr\u00e9ateurs de marque, des cr\u00e9ateurs de contenu, des gestionnaires de r\u00e9putation et des strat\u00e8ges. Avec une \u00e9quipe d'anciens directeurs g\u00e9n\u00e9raux, de directeurs des relations publiques internationales et de r\u00e9dacteurs en chef de magazines nationaux, nous allons au-del\u00e0 des relations publiques pour aider \u00e0 fa\u00e7onner la strat\u00e9gie commerciale globale de tous nos clients.<\/p>","protected":false},"excerpt":{"rendered":"<p>Relations publiques de l'\u00e9v\u00e9nement : Damon Hill OBE a inaugur\u00e9 aujourd'hui Autosport International et sera la vedette du salon ce week-end. Hill c\u00e9l\u00e8bre au NEC le 20e anniversaire de sa victoire au championnat du monde de F1 en 1996. Plus t\u00f4t ce...<\/p>","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1024","post","type-post","status-publish","format-standard","hentry","category-uncategorised"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Damon Hill OBE at Autosport International - Influence Associates<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/influenceassociates.com\/fr\/1024-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Damon Hill OBE at Autosport International - Influence Associates\" \/>\n<meta property=\"og:description\" content=\"Event PR: Damon Hill OBE has opened Autosport International today and is starring at the show this weekend. Hill is celebrating the 20th anniversary of his 1996 F1 World Championship win at the NEC. Earlier this&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/influenceassociates.com\/fr\/1024-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Influence Associates\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-16T14:44:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-05-06T14:30:29+00:00\" \/>\n<meta name=\"author\" content=\"Influence iNews Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@InfluenceComms\" \/>\n<meta name=\"twitter:site\" content=\"@InfluenceComms\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Influence iNews Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/1024-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/1024-2\\\/\"},\"author\":{\"name\":\"Influence iNews Team\",\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/#\\\/schema\\\/person\\\/12578eb426032924a60797cb1629f68b\"},\"headline\":\"Damon Hill OBE at Autosport International\",\"datePublished\":\"2016-01-16T14:44:55+00:00\",\"dateModified\":\"2016-05-06T14:30:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/1024-2\\\/\"},\"wordCount\":572,\"articleSection\":[\"Uncategorised\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/1024-2\\\/\",\"url\":\"https:\\\/\\\/influenceassociates.com\\\/1024-2\\\/\",\"name\":\"Damon Hill OBE at Autosport International - Influence Associates\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/#website\"},\"datePublished\":\"2016-01-16T14:44:55+00:00\",\"dateModified\":\"2016-05-06T14:30:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/#\\\/schema\\\/person\\\/12578eb426032924a60797cb1629f68b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/1024-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/influenceassociates.com\\\/1024-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/1024-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/influenceassociates.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Damon Hill OBE at Autosport International\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/#website\",\"url\":\"https:\\\/\\\/influenceassociates.com\\\/\",\"name\":\"Influence Associates\",\"description\":\"Communications &amp; PR, Brand Strategy and Reputation Management\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/influenceassociates.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/#\\\/schema\\\/person\\\/12578eb426032924a60797cb1629f68b\",\"name\":\"Influence iNews Team\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Damon Hill OBE \u00e0 Autosport International - Influence Associates","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/influenceassociates.com\/fr\/1024-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Damon Hill OBE at Autosport International - Influence Associates","og_description":"Event PR: Damon Hill OBE has opened Autosport International today and is starring at the show this weekend. Hill is celebrating the 20th anniversary of his 1996 F1 World Championship win at the NEC. Earlier this&hellip;","og_url":"https:\/\/influenceassociates.com\/fr\/1024-2\/","og_site_name":"Influence Associates","article_published_time":"2016-01-16T14:44:55+00:00","article_modified_time":"2016-05-06T14:30:29+00:00","author":"Influence iNews Team","twitter_card":"summary_large_image","twitter_creator":"@InfluenceComms","twitter_site":"@InfluenceComms","twitter_misc":{"\u00c9crit par":"Influence iNews Team","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/influenceassociates.com\/1024-2\/#article","isPartOf":{"@id":"https:\/\/influenceassociates.com\/1024-2\/"},"author":{"name":"Influence iNews Team","@id":"https:\/\/influenceassociates.com\/#\/schema\/person\/12578eb426032924a60797cb1629f68b"},"headline":"Damon Hill OBE at Autosport International","datePublished":"2016-01-16T14:44:55+00:00","dateModified":"2016-05-06T14:30:29+00:00","mainEntityOfPage":{"@id":"https:\/\/influenceassociates.com\/1024-2\/"},"wordCount":572,"articleSection":["Uncategorised"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/influenceassociates.com\/1024-2\/","url":"https:\/\/influenceassociates.com\/1024-2\/","name":"Damon Hill OBE \u00e0 Autosport International - Influence Associates","isPartOf":{"@id":"https:\/\/influenceassociates.com\/#website"},"datePublished":"2016-01-16T14:44:55+00:00","dateModified":"2016-05-06T14:30:29+00:00","author":{"@id":"https:\/\/influenceassociates.com\/#\/schema\/person\/12578eb426032924a60797cb1629f68b"},"breadcrumb":{"@id":"https:\/\/influenceassociates.com\/1024-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/influenceassociates.com\/1024-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/influenceassociates.com\/1024-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/influenceassociates.com\/"},{"@type":"ListItem","position":2,"name":"Damon Hill OBE at Autosport International"}]},{"@type":"WebSite","@id":"https:\/\/influenceassociates.com\/#website","url":"https:\/\/influenceassociates.com\/","name":"Associ\u00e9s d'influence","description":"Communications et relations publiques, strat\u00e9gie de marque et gestion de la r\u00e9putation","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/influenceassociates.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/influenceassociates.com\/#\/schema\/person\/12578eb426032924a60797cb1629f68b","name":"L'\u00e9quipe d'Influence iNews"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/influenceassociates.com\/fr\/wp-json\/wp\/v2\/posts\/1024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influenceassociates.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influenceassociates.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influenceassociates.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/influenceassociates.com\/fr\/wp-json\/wp\/v2\/comments?post=1024"}],"version-history":[{"count":0,"href":"https:\/\/influenceassociates.com\/fr\/wp-json\/wp\/v2\/posts\/1024\/revisions"}],"wp:attachment":[{"href":"https:\/\/influenceassociates.com\/fr\/wp-json\/wp\/v2\/media?parent=1024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influenceassociates.com\/fr\/wp-json\/wp\/v2\/categories?post=1024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influenceassociates.com\/fr\/wp-json\/wp\/v2\/tags?post=1024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}