{"id":4434,"date":"2017-11-29T17:32:40","date_gmt":"2017-11-29T17:32:40","guid":{"rendered":"http:\/\/influenceassociates.com\/?p=4434"},"modified":"2020-03-02T16:40:55","modified_gmt":"2020-03-02T16:40:55","slug":"lynk-co-01-voiture-la-plus-vendue","status":"publish","type":"post","link":"https:\/\/influenceassociates.com\/fr\/lynk-co-01-fastest-selling-car\/","title":{"rendered":"Lynk &amp; Co : 01 Voiture la plus vendue"},"content":{"rendered":"<p><a href=\"https:\/\/www.lynkco.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Lynk &amp; Co<\/a>la marque de mobilit\u00e9 connect\u00e9e et partageable con\u00e7ue et fabriqu\u00e9e en Su\u00e8de, annonce le d\u00e9but des ventes - un an seulement apr\u00e8s la naissance de l'entreprise.<\/p>\n<p>La premi\u00e8re boutique en ligne de Lynk &amp; Co, qui a ouvert ses portes pour les \"pr\u00e9ventes\" le 17 novembre, a re\u00e7u 6 000 commandes pour le mod\u00e8le 01 en seulement 2 minutes et 17 secondes, d\u00e9passant ainsi toutes les attentes et enregistrant un d\u00e9marrage record des ventes.<\/p>\n<p>Les trois jours de pr\u00e9vente pr\u00e9vus ayant \u00e9t\u00e9 enti\u00e8rement \u00e9coul\u00e9s en seulement 137 secondes, la Lynk &amp; Co 01 est devenue la voiture la plus rapidement vendue au monde, avant le d\u00e9but officiel des ventes en volume le 28 novembre.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4435 size-medium\" title=\"Auto Tech PR : Lynk and Co\" src=\"https:\/\/influenceassociates.com\/wordpress-cms\/wp-content\/uploads\/2017\/11\/LynkCo_Sales_Launch_6-339x339.jpg\" alt=\"Auto Tech PR : Lynk and Co\" width=\"339\" height=\"339\" srcset=\"https:\/\/influenceassociates.com\/wordpress-cms\/wp-content\/uploads\/2017\/11\/LynkCo_Sales_Launch_6-339x339.jpg 339w, https:\/\/influenceassociates.com\/wordpress-cms\/wp-content\/uploads\/2017\/11\/LynkCo_Sales_Launch_6-150x150.jpg 150w, https:\/\/influenceassociates.com\/wordpress-cms\/wp-content\/uploads\/2017\/11\/LynkCo_Sales_Launch_6-356x356.jpg 356w, https:\/\/influenceassociates.com\/wordpress-cms\/wp-content\/uploads\/2017\/11\/LynkCo_Sales_Launch_6-148x148.jpg 148w\" sizes=\"auto, (max-width: 339px) 100vw, 339px\" \/><\/p>\n<p><strong><em>Alain Visser, Se<\/em><\/strong><strong><em>nior Vice President of Lyn<\/em><\/strong><strong><em>k &amp; Co :<\/em><\/strong><\/p>\n<p><em>\"Nous avons annonc\u00e9 la naissance de Lynk &amp; Co il y a presque exactement un an. Aujourd'hui, \u00e0 peine 12<\/em>\u00a0mois plus tard,\u00a0<em>nous d\u00e9marrons les ventes de notre SUV 01 connect\u00e9 et partageable de mani\u00e8re record.<\/em>\u00a0<em>Que vous choisissiez de vous inscrire en ligne ou en magasin, nous vous promettons une exp\u00e9rience unique et agr\u00e9able.<\/em><\/p>\n<p><em>En ligne, rien de plus simple : nous avons reproduit l'exp\u00e9rience en magasin et la simplicit\u00e9 du choix gr\u00e2ce \u00e0 notre carrousel \"explorateur\" unique. Il suffit de s'arr\u00eater sur la voiture qui vous pla\u00eet et de souscrire en ligne - c'est aussi simple que cela, comme l'ont prouv\u00e9 les clients chinois lors de notre \u00e9v\u00e9nement de pr\u00e9vente.<\/em><\/p>\n<p><em>Nous sommes immens\u00e9ment fiers de la rapidit\u00e9 et de l'ampleur de notre lancement. Nous avions promis de tout bouleverser et de tout chambouler, et c'est maintenant que le voyage commence vraiment\".<\/em><\/p>\n<p>\u00c0 partir du 28 novembre, les ventes d\u00e9buteront officiellement avec l'ouverture de quelque 150 boutiques et magasins de marque dans toute la Chine, o\u00f9 les visiteurs seront accueillis dans un cadre ouvert et convivial comprenant un caf\u00e9-bar, un cin\u00e9ma et une aire de jeux pour les enfants.<\/p>\n<p>Lynk &amp; Co a abandonn\u00e9 le concept automobile traditionnel des mod\u00e8les de base, des points d'entr\u00e9e et des listes d'options interminables. Inspir\u00e9s par les mondes de la mode et de la technologie, les niveaux de finition et les options sont remplac\u00e9s par une simple s\u00e9lection de mod\u00e8les enti\u00e8rement \u00e9quip\u00e9s et \u00e0 prix unique.\u00a0<em>collections<\/em>.<\/p>\n<p>Les prix des premi\u00e8res collections de la s\u00e9rie 01 sont annonc\u00e9s aujourd'hui pour le march\u00e9 chinois uniquement, et commencent \u00e0 158 800 RMB, pour atteindre 202 800 RMB.<\/p>\n<p>Les premi\u00e8res collections de SUV 01 aux sp\u00e9cifications chinoises sont \u00e9quip\u00e9es de moteurs \u00e0 essence d\u00e9riv\u00e9s de Volvo. Lorsque la production pour l'Europe commencera, de nouveaux groupes motopropulseurs \u00e9lectrifi\u00e9s seront propos\u00e9s de s\u00e9rie, avec davantage de technologies et de fonctions de connectivit\u00e9. Les prix en Europe seront plus \u00e9lev\u00e9s que ceux de la premi\u00e8re g\u00e9n\u00e9ration de collections d\u00e9voil\u00e9es en Chine.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4438 size-medium\" title=\"Auto Tech PR : Lynk and Co\" src=\"https:\/\/influenceassociates.com\/wordpress-cms\/wp-content\/uploads\/2017\/11\/LynkCo_Sales_Launch_11-339x339.jpg\" alt=\"Auto Tech PR : Lynk and Co\" width=\"339\" height=\"339\" srcset=\"https:\/\/influenceassociates.com\/wordpress-cms\/wp-content\/uploads\/2017\/11\/LynkCo_Sales_Launch_11-339x339.jpg 339w, https:\/\/influenceassociates.com\/wordpress-cms\/wp-content\/uploads\/2017\/11\/LynkCo_Sales_Launch_11-150x150.jpg 150w, https:\/\/influenceassociates.com\/wordpress-cms\/wp-content\/uploads\/2017\/11\/LynkCo_Sales_Launch_11-356x356.jpg 356w, https:\/\/influenceassociates.com\/wordpress-cms\/wp-content\/uploads\/2017\/11\/LynkCo_Sales_Launch_11-148x148.jpg 148w\" sizes=\"auto, (max-width: 339px) 100vw, 339px\" \/><\/p>\n<p><strong><em>Alain Visser ajoute :<\/em><\/strong><\/p>\n<p><em>\"En ligne et dans nos magasins, nous \u00e9liminons l'anxi\u00e9t\u00e9 li\u00e9e au fait de cocher des cases d'options et la pression li\u00e9e au choix de la bonne sp\u00e9cification. Nous voulons faire tomber les barri\u00e8res \u00e0 l'acquisition d'une voiture. Pas de combinaisons compliqu\u00e9es, pas de d\u00e9cisions \u00e0 prendre, pas de n\u00e9gociations. Notre offre \u00e0 prix fixe, notre mod\u00e8le d'abonnement, la connectivit\u00e9 gratuite et la garantie \u00e0 vie s'occupent de tous les d\u00e9tails ennuyeux et compliqu\u00e9s, ce qui permet au client de se concentrer sur les choses amusantes.<\/em><\/p>\n<p>La connectivit\u00e9 est au c\u0153ur de la marque Lynk &amp; Co. Les clients trouveront une gamme de technologies connect\u00e9es dans les v\u00e9hicules, allant d'une fonction de partage avec le premier bouton de partage embarqu\u00e9 au monde, \u00e0 la recharge sans fil et \u00e0 une boutique d'applications Lynk &amp; Co d\u00e9di\u00e9e, toutes destin\u00e9es \u00e0 faciliter la vie lors des d\u00e9placements. D\u00e9crits comme un \"smartphone sur roues\", tous les mod\u00e8les sont \u00e9quip\u00e9s d'un grand \u00e9cran tactile central et de syst\u00e8mes t\u00e9l\u00e9matiques, toujours connect\u00e9s \u00e0 Internet et au cloud de la voiture.<\/p>\n<p>Con\u00e7ue et fabriqu\u00e9e par une \u00e9quipe internationale \u00e0 G\u00f6teborg, en Su\u00e8de, Lynk &amp; Co a un c\u0153ur et une \u00e2me europ\u00e9ens, et une approche rafra\u00eechissante du mod\u00e8le commercial de l'automobile en tant que nouvelle marque de mobilit\u00e9 urbaine. Des services personnalis\u00e9s, une API (interface de programmation d'applications) ouverte (la premi\u00e8re \u00e0 \u00eatre \"ouverte\" dans le secteur automobile), une connectivit\u00e9 in\u00e9gal\u00e9e, le partage de v\u00e9hicules, le commerce \u00e9lectronique, la propri\u00e9t\u00e9 simple par abonnement et le premier magasin d'applications d\u00e9di\u00e9 aux voitures : telles sont les principales offres de Lynk &amp; Co.<\/p>\n<p>Avec sa nouvelle gamme de voitures \u00e0 la pointe de la technologie et des options de propri\u00e9t\u00e9 simples et sans tracas \u00e0 des prix accessibles, Lynk &amp; Co vise \u00e0 remettre en question et \u00e0 red\u00e9finir la mani\u00e8re dont les produits automobiles sont achet\u00e9s, poss\u00e9d\u00e9s et utilis\u00e9s dans le monde entier.<\/p>\n<p><i><a href=\"http:\/\/influenceassociates.com\/fr\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?hl=en-GB&amp;q=http:\/\/influenceassociates.com\/&amp;source=gmail&amp;ust=1500024003973000&amp;usg=AFQjCNEMdi2XETCX9OGQ8WVaA6MxL3t6ng\">Associ\u00e9s d'influence<\/a>\u00a0sont des leaders mondiaux en mati\u00e8re de relations publiques dans les domaines de l'automobile, du sport automobile, de l'automobile technique et des voitures de collection, ainsi qu'en mati\u00e8re de strat\u00e9gie et de d\u00e9veloppement de la marque, de relations publiques et de communication.<\/i><\/p>","protected":false},"excerpt":{"rendered":"<p>Lynk &amp; Co, la marque de mobilit\u00e9 connect\u00e9e et partageable con\u00e7ue et fabriqu\u00e9e en Su\u00e8de, annonce le d\u00e9but des ventes - un an seulement apr\u00e8s la naissance de l'entreprise. La premi\u00e8re boutique en ligne de Lynk &amp; Co, qui a...<\/p>","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4434","post","type-post","status-publish","format-standard","hentry","category-uncategorised"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lynk &amp; Co: 01 Fastest Selling Car - Influence Associates<\/title>\n<meta name=\"description\" content=\"Lynk &amp; Co, the connected and shareable mobility brand designed and engineered in Sweden, announces the start of sales \u2013 one year after the company\u2019s birth.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/influenceassociates.com\/fr\/lynk-co-01-voiture-la-plus-vendue\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lynk &amp; Co: 01 Fastest Selling Car - Influence Associates\" \/>\n<meta property=\"og:description\" content=\"Lynk &amp; Co, the connected and shareable mobility brand designed and engineered in Sweden, announces the start of sales \u2013 one year after the company\u2019s birth.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/influenceassociates.com\/fr\/lynk-co-01-voiture-la-plus-vendue\/\" \/>\n<meta property=\"og:site_name\" content=\"Influence Associates\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-29T17:32:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-02T16:40:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/influenceassociates.com\/wordpress-cms\/wp-content\/uploads\/2017\/11\/LynkCo_Sales_Launch_6-339x339.jpg\" \/>\n<meta name=\"author\" content=\"Influence iNews Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@InfluenceComms\" \/>\n<meta name=\"twitter:site\" content=\"@InfluenceComms\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Influence iNews Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/lynk-co-01-fastest-selling-car\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/lynk-co-01-fastest-selling-car\\\/\"},\"author\":{\"name\":\"Influence iNews Team\",\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/#\\\/schema\\\/person\\\/12578eb426032924a60797cb1629f68b\"},\"headline\":\"Lynk &#038; Co: 01 Fastest Selling Car\",\"datePublished\":\"2017-11-29T17:32:40+00:00\",\"dateModified\":\"2020-03-02T16:40:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/lynk-co-01-fastest-selling-car\\\/\"},\"wordCount\":672,\"image\":{\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/lynk-co-01-fastest-selling-car\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/influenceassociates.com\\\/wordpress-cms\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/LynkCo_Sales_Launch_6-339x339.jpg\",\"articleSection\":[\"Uncategorised\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/lynk-co-01-fastest-selling-car\\\/\",\"url\":\"https:\\\/\\\/influenceassociates.com\\\/lynk-co-01-fastest-selling-car\\\/\",\"name\":\"Lynk & Co: 01 Fastest Selling Car - Influence Associates\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/lynk-co-01-fastest-selling-car\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/lynk-co-01-fastest-selling-car\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/influenceassociates.com\\\/wordpress-cms\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/LynkCo_Sales_Launch_6-339x339.jpg\",\"datePublished\":\"2017-11-29T17:32:40+00:00\",\"dateModified\":\"2020-03-02T16:40:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/#\\\/schema\\\/person\\\/12578eb426032924a60797cb1629f68b\"},\"description\":\"Lynk & Co, the connected and shareable mobility brand designed and engineered in Sweden, announces the start of sales \u2013 one year after the company\u2019s birth.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/lynk-co-01-fastest-selling-car\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/influenceassociates.com\\\/lynk-co-01-fastest-selling-car\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/lynk-co-01-fastest-selling-car\\\/#primaryimage\",\"url\":\"https:\\\/\\\/influenceassociates.com\\\/wordpress-cms\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/LynkCo_Sales_Launch_6-339x339.jpg\",\"contentUrl\":\"https:\\\/\\\/influenceassociates.com\\\/wordpress-cms\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/LynkCo_Sales_Launch_6-339x339.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/lynk-co-01-fastest-selling-car\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/influenceassociates.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lynk &#038; Co: 01 Fastest Selling Car\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/#website\",\"url\":\"https:\\\/\\\/influenceassociates.com\\\/\",\"name\":\"Influence Associates\",\"description\":\"Communications &amp; PR, Brand Strategy and Reputation Management\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/influenceassociates.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/#\\\/schema\\\/person\\\/12578eb426032924a60797cb1629f68b\",\"name\":\"Influence iNews Team\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lynk &amp; Co : 01 Voiture la plus vendue - Influence Associates","description":"Lynk &amp; Co, la marque de mobilit\u00e9 connect\u00e9e et partageable con\u00e7ue et fabriqu\u00e9e en Su\u00e8de, annonce le d\u00e9but des ventes - un an apr\u00e8s la naissance de l'entreprise.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/influenceassociates.com\/fr\/lynk-co-01-voiture-la-plus-vendue\/","og_locale":"fr_FR","og_type":"article","og_title":"Lynk & Co: 01 Fastest Selling Car - Influence Associates","og_description":"Lynk & Co, the connected and shareable mobility brand designed and engineered in Sweden, announces the start of sales \u2013 one year after the company\u2019s birth.","og_url":"https:\/\/influenceassociates.com\/fr\/lynk-co-01-voiture-la-plus-vendue\/","og_site_name":"Influence Associates","article_published_time":"2017-11-29T17:32:40+00:00","article_modified_time":"2020-03-02T16:40:55+00:00","og_image":[{"url":"https:\/\/influenceassociates.com\/wordpress-cms\/wp-content\/uploads\/2017\/11\/LynkCo_Sales_Launch_6-339x339.jpg","type":"","width":"","height":""}],"author":"Influence iNews Team","twitter_card":"summary_large_image","twitter_creator":"@InfluenceComms","twitter_site":"@InfluenceComms","twitter_misc":{"\u00c9crit par":"Influence iNews Team","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/influenceassociates.com\/lynk-co-01-fastest-selling-car\/#article","isPartOf":{"@id":"https:\/\/influenceassociates.com\/lynk-co-01-fastest-selling-car\/"},"author":{"name":"Influence iNews Team","@id":"https:\/\/influenceassociates.com\/#\/schema\/person\/12578eb426032924a60797cb1629f68b"},"headline":"Lynk &#038; Co: 01 Fastest Selling Car","datePublished":"2017-11-29T17:32:40+00:00","dateModified":"2020-03-02T16:40:55+00:00","mainEntityOfPage":{"@id":"https:\/\/influenceassociates.com\/lynk-co-01-fastest-selling-car\/"},"wordCount":672,"image":{"@id":"https:\/\/influenceassociates.com\/lynk-co-01-fastest-selling-car\/#primaryimage"},"thumbnailUrl":"https:\/\/influenceassociates.com\/wordpress-cms\/wp-content\/uploads\/2017\/11\/LynkCo_Sales_Launch_6-339x339.jpg","articleSection":["Uncategorised"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/influenceassociates.com\/lynk-co-01-fastest-selling-car\/","url":"https:\/\/influenceassociates.com\/lynk-co-01-fastest-selling-car\/","name":"Lynk &amp; Co : 01 Voiture la plus vendue - Influence Associates","isPartOf":{"@id":"https:\/\/influenceassociates.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/influenceassociates.com\/lynk-co-01-fastest-selling-car\/#primaryimage"},"image":{"@id":"https:\/\/influenceassociates.com\/lynk-co-01-fastest-selling-car\/#primaryimage"},"thumbnailUrl":"https:\/\/influenceassociates.com\/wordpress-cms\/wp-content\/uploads\/2017\/11\/LynkCo_Sales_Launch_6-339x339.jpg","datePublished":"2017-11-29T17:32:40+00:00","dateModified":"2020-03-02T16:40:55+00:00","author":{"@id":"https:\/\/influenceassociates.com\/#\/schema\/person\/12578eb426032924a60797cb1629f68b"},"description":"Lynk &amp; Co, la marque de mobilit\u00e9 connect\u00e9e et partageable con\u00e7ue et fabriqu\u00e9e en Su\u00e8de, annonce le d\u00e9but des ventes - un an apr\u00e8s la naissance de l'entreprise.","breadcrumb":{"@id":"https:\/\/influenceassociates.com\/lynk-co-01-fastest-selling-car\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/influenceassociates.com\/lynk-co-01-fastest-selling-car\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/influenceassociates.com\/lynk-co-01-fastest-selling-car\/#primaryimage","url":"https:\/\/influenceassociates.com\/wordpress-cms\/wp-content\/uploads\/2017\/11\/LynkCo_Sales_Launch_6-339x339.jpg","contentUrl":"https:\/\/influenceassociates.com\/wordpress-cms\/wp-content\/uploads\/2017\/11\/LynkCo_Sales_Launch_6-339x339.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/influenceassociates.com\/lynk-co-01-fastest-selling-car\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/influenceassociates.com\/"},{"@type":"ListItem","position":2,"name":"Lynk &#038; Co: 01 Fastest Selling Car"}]},{"@type":"WebSite","@id":"https:\/\/influenceassociates.com\/#website","url":"https:\/\/influenceassociates.com\/","name":"Associ\u00e9s d'influence","description":"Communications et relations publiques, strat\u00e9gie de marque et gestion de la r\u00e9putation","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/influenceassociates.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/influenceassociates.com\/#\/schema\/person\/12578eb426032924a60797cb1629f68b","name":"L'\u00e9quipe d'Influence iNews"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/influenceassociates.com\/fr\/wp-json\/wp\/v2\/posts\/4434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influenceassociates.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influenceassociates.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influenceassociates.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/influenceassociates.com\/fr\/wp-json\/wp\/v2\/comments?post=4434"}],"version-history":[{"count":0,"href":"https:\/\/influenceassociates.com\/fr\/wp-json\/wp\/v2\/posts\/4434\/revisions"}],"wp:attachment":[{"href":"https:\/\/influenceassociates.com\/fr\/wp-json\/wp\/v2\/media?parent=4434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influenceassociates.com\/fr\/wp-json\/wp\/v2\/categories?post=4434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influenceassociates.com\/fr\/wp-json\/wp\/v2\/tags?post=4434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}