{"id":980,"date":"2016-01-14T16:54:46","date_gmt":"2016-01-14T16:54:46","guid":{"rendered":"https:\/\/influenceassociates.com\/wordpress-cms\/?p=980"},"modified":"2016-05-06T15:16:32","modified_gmt":"2016-05-06T14:16:32","slug":"carwow-leve-125-millions-de-dollars-dans-le-cadre-de-la-serie-b-sous-la-direction-dacell","status":"publish","type":"post","link":"https:\/\/influenceassociates.com\/fr\/carwow-raises-12-5-million-series-b-led-by-acell\/","title":{"rendered":"Carwow l\u00e8ve un investissement de 12,5 millions de livres sterling"},"content":{"rendered":"<p>Relations publiques dans le secteur automobile :<\/p>\n<p>carwow, le site qui offre une meilleure fa\u00e7on d'acheter une nouvelle voiture, annonce aujourd'hui un investissement de s\u00e9rie B de 12,5 millions de livres sterling ($18,75 millions) men\u00e9 par Accel. Les investisseurs pr\u00e9c\u00e9dents, Balderton Capital, Samos Investments et Episode 1 Ventures, son premier bailleur de fonds, ont \u00e9galement particip\u00e9 \u00e0 ce tour de table, qui fait suite \u00e0 un investissement de s\u00e9rie A de 4,6 millions de livres sterling en d\u00e9cembre 2014. L'investissement alimentera la croissance de l'entreprise qui continue \u00e0 transformer l'exp\u00e9rience d'achat d'une voiture pour les consommateurs et les concessionnaires.<\/p>\n<p>carwow a \u00e9t\u00e9 lanc\u00e9 par James Hind (PDG), Alexandra Margolis et David Santoro en 2013 pour faire de l'achat d'une voiture une exp\u00e9rience agr\u00e9able, de la d\u00e9couverte \u00e0 l'achat. La plateforme bouleverse le processus traditionnel d'achat d'une voiture : les acheteurs choisissent la voiture qui leur pla\u00eet, puis carwow envoie jusqu'\u00e0 cinq offres de la part des concessionnaires les mieux not\u00e9s de Grande-Bretagne. S'il est int\u00e9ress\u00e9, l'acheteur peut contacter le concessionnaire de mani\u00e8re anonyme par l'interm\u00e9diaire du syst\u00e8me carwow et acheter la voiture directement aupr\u00e8s du concessionnaire.<\/p>\n<p>Le service est gratuit pour les consommateurs et, gr\u00e2ce \u00e0 carwow, les acheteurs \u00e9conomisent en moyenne 3 600 livres sterling sur le prix d'une nouvelle voiture, tandis que les concessionnaires b\u00e9n\u00e9ficient de co\u00fbts de marketing r\u00e9duits, d'un processus de vente plus rapide et d'une exposition \u00e0 un march\u00e9 cible plus jeune et plus \u00e0 l'aise sur le web.<\/p>\n<p>Les consommateurs et les concessionnaires profitent des avantages d'un site web magnifiquement con\u00e7u qui permet aux acheteurs de voitures d'obtenir la bonne voiture \u00e0 un prix avantageux aupr\u00e8s d'un excellent concessionnaire. Plus de 400 millions de livres sterling de voitures ont \u00e9t\u00e9 achet\u00e9es par l'interm\u00e9diaire de la plateforme.<\/p>\n<p>Traditionnellement, les acheteurs doivent se rendre chez plusieurs concessionnaires avant d'effectuer un achat, tandis que les concessionnaires doivent consacrer beaucoup de temps et de ressources \u00e0 une longue exp\u00e9rience de vente. Ni les acheteurs ni les concessionnaires n'appr\u00e9cient la partie souvent difficile du processus de marchandage des prix.<\/p>\n<p>M. Hind a d\u00e9clar\u00e9 : \"Nous sommes ravis d'\u00e9tendre encore davantage notre service apr\u00e8s la forte croissance enregistr\u00e9e en 2015. Une nouvelle voiture est un achat important, g\u00e9n\u00e9ralement le plus important d'une personne apr\u00e8s sa maison. Chez carwow, nous aimons travailler avec l'industrie pour rendre les choses plus simples et plus efficaces pour toutes les parties concern\u00e9es. Cette nouvelle lev\u00e9e de fonds nous donne la puissance de feu dont nous avons besoin pour changer la fa\u00e7on dont les Britanniques ach\u00e8tent des voitures\".<\/p>\n<p>Zeinab Salem, de Mercedes-Benz of Grimsby, a d\u00e9clar\u00e9 : \"Les acheteurs de voitures sont tellement mieux inform\u00e9s aujourd'hui, et il est probable qu'ils aient choisi la marque et le mod\u00e8le de la voiture qu'ils veulent acheter avant m\u00eame d'avoir mis les pieds dans une salle d'exposition - ils ont simplement besoin de prendre une d\u00e9cision inform\u00e9e et \u00e9duqu\u00e9e quant \u00e0 l'acheteur de la voiture. carwow est un moyen fantastique et innovant pour les clients de comparer les offres disponibles sur le march\u00e9, et il oblige les concessionnaires \u00e0 se battre plus fort pour leur pr\u00e9cieuse affaire.<\/p>\n<p>Carwow utilisera ce nouveau financement pour poursuivre sa croissance en d\u00e9veloppant sa marque et son marketing. En outre, l'entreprise cherchera \u00e0 am\u00e9liorer ses services gr\u00e2ce \u00e0 de nouveaux produits et \u00e0 de nouvelles offres.<\/p>\n<p>Dans le cadre de cet investissement, Fred Destin, partenaire d'Accel, rejoindra le conseil d'administration. Destin a d\u00e9clar\u00e9 : \"Carwow me rappelle Zoopla \u00e0 ses d\u00e9buts : \"carwow me rappelle Zoopla \u00e0 ses d\u00e9buts - ils sont en train de changer l'exp\u00e9rience de la d\u00e9couverte gr\u00e2ce \u00e0 une superbe plateforme en ligne et \u00e0 de meilleures informations, et ils cr\u00e9ent une situation gagnant-gagnant pour les consommateurs et les concessionnaires, gr\u00e2ce \u00e0 une merveilleuse \u00e9quipe fondatrice.<\/p>\n<p>Rob Moffat, partenaire de Balderton Capital, a d\u00e9clar\u00e9 : \"La soci\u00e9t\u00e9 s'est multipli\u00e9e par plus de 10 et a mis en place une excellente op\u00e9ration depuis le premier investissement de Balderton il y a deux ans. Mais l'\u00e9quipe fondatrice ne veut pas s'arr\u00eater l\u00e0 et a des ambitions bien plus grandes. Nous pensons que carwow est en mesure de mener l'\u00e9volution de la vente au d\u00e9tail de voitures dans les ann\u00e9es \u00e0 venir\".<\/p>\n<p>&nbsp;<\/p>\n<p>Influence Associates a \u00e9t\u00e9 cr\u00e9\u00e9e pour \u00eatre la meilleure agence de relations publiques dans le domaine de l'automobile, du sport automobile et des voitures de collection au monde. Avec l'\u00e9quipe de direction la plus exp\u00e9riment\u00e9e du secteur des relations publiques automobiles, nous sommes parfaitement plac\u00e9s pour fournir un service de premier ordre \u00e0 notre portefeuille de clients de premier ordre.<\/p>\n<p>Nous sommes des cr\u00e9ateurs de marque, des cr\u00e9ateurs de contenu, des gestionnaires de r\u00e9putation et des strat\u00e8ges. Avec une \u00e9quipe d'anciens directeurs g\u00e9n\u00e9raux, de directeurs des relations publiques internationales et de r\u00e9dacteurs en chef de magazines nationaux, nous allons au-del\u00e0 des relations publiques pour aider \u00e0 fa\u00e7onner la strat\u00e9gie commerciale globale de tous nos clients.<\/p>","protected":false},"excerpt":{"rendered":"<p>Automotive PR : carwow, le site qui offre une meilleure fa\u00e7on d'acheter une nouvelle voiture, annonce aujourd'hui un investissement de s\u00e9rie B de 12,5 millions de livres sterling ($18,75 millions) men\u00e9 par Accel. Les investisseurs pr\u00e9c\u00e9dents, Balderton Capital, Samos Investments et Episode...<\/p>","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-980","post","type-post","status-publish","format-standard","hentry","category-uncategorised"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>carwow raises \u00a312.5 Million of investment - Influence Associates<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/influenceassociates.com\/fr\/carwow-leve-125-millions-de-dollars-dans-le-cadre-de-la-serie-b-sous-la-direction-dacell\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"carwow raises \u00a312.5 Million of investment - Influence Associates\" \/>\n<meta property=\"og:description\" content=\"Automotive PR: carwow, the site that offers a better way to buy a new car, today announces a \u00a312.5 million ($18.75 million) Series B investment led by Accel. Previous investors Balderton Capital, Samos Investments and Episode&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/influenceassociates.com\/fr\/carwow-leve-125-millions-de-dollars-dans-le-cadre-de-la-serie-b-sous-la-direction-dacell\/\" \/>\n<meta property=\"og:site_name\" content=\"Influence Associates\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-14T16:54:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-05-06T14:16:32+00:00\" \/>\n<meta name=\"author\" content=\"Influence iNews Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@InfluenceComms\" \/>\n<meta name=\"twitter:site\" content=\"@InfluenceComms\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Influence iNews Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/carwow-raises-12-5-million-series-b-led-by-acell\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/carwow-raises-12-5-million-series-b-led-by-acell\\\/\"},\"author\":{\"name\":\"Influence iNews Team\",\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/#\\\/schema\\\/person\\\/12578eb426032924a60797cb1629f68b\"},\"headline\":\"carwow raises \u00a312.5 Million of investment\",\"datePublished\":\"2016-01-14T16:54:46+00:00\",\"dateModified\":\"2016-05-06T14:16:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/carwow-raises-12-5-million-series-b-led-by-acell\\\/\"},\"wordCount\":669,\"articleSection\":[\"Uncategorised\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/carwow-raises-12-5-million-series-b-led-by-acell\\\/\",\"url\":\"https:\\\/\\\/influenceassociates.com\\\/carwow-raises-12-5-million-series-b-led-by-acell\\\/\",\"name\":\"carwow raises \u00a312.5 Million of investment - Influence Associates\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/#website\"},\"datePublished\":\"2016-01-14T16:54:46+00:00\",\"dateModified\":\"2016-05-06T14:16:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/#\\\/schema\\\/person\\\/12578eb426032924a60797cb1629f68b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/carwow-raises-12-5-million-series-b-led-by-acell\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/influenceassociates.com\\\/carwow-raises-12-5-million-series-b-led-by-acell\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/carwow-raises-12-5-million-series-b-led-by-acell\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/influenceassociates.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"carwow raises \u00a312.5 Million of investment\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/#website\",\"url\":\"https:\\\/\\\/influenceassociates.com\\\/\",\"name\":\"Influence Associates\",\"description\":\"Communications &amp; PR, Brand Strategy and Reputation Management\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/influenceassociates.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/influenceassociates.com\\\/#\\\/schema\\\/person\\\/12578eb426032924a60797cb1629f68b\",\"name\":\"Influence iNews Team\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"carwow l\u00e8ve 12,5 millions de livres sterling d'investissement - Influence Associates","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/influenceassociates.com\/fr\/carwow-leve-125-millions-de-dollars-dans-le-cadre-de-la-serie-b-sous-la-direction-dacell\/","og_locale":"fr_FR","og_type":"article","og_title":"carwow raises \u00a312.5 Million of investment - Influence Associates","og_description":"Automotive PR: carwow, the site that offers a better way to buy a new car, today announces a \u00a312.5 million ($18.75 million) Series B investment led by Accel. Previous investors Balderton Capital, Samos Investments and Episode&hellip;","og_url":"https:\/\/influenceassociates.com\/fr\/carwow-leve-125-millions-de-dollars-dans-le-cadre-de-la-serie-b-sous-la-direction-dacell\/","og_site_name":"Influence Associates","article_published_time":"2016-01-14T16:54:46+00:00","article_modified_time":"2016-05-06T14:16:32+00:00","author":"Influence iNews Team","twitter_card":"summary_large_image","twitter_creator":"@InfluenceComms","twitter_site":"@InfluenceComms","twitter_misc":{"\u00c9crit par":"Influence iNews Team","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/influenceassociates.com\/carwow-raises-12-5-million-series-b-led-by-acell\/#article","isPartOf":{"@id":"https:\/\/influenceassociates.com\/carwow-raises-12-5-million-series-b-led-by-acell\/"},"author":{"name":"Influence iNews Team","@id":"https:\/\/influenceassociates.com\/#\/schema\/person\/12578eb426032924a60797cb1629f68b"},"headline":"carwow raises \u00a312.5 Million of investment","datePublished":"2016-01-14T16:54:46+00:00","dateModified":"2016-05-06T14:16:32+00:00","mainEntityOfPage":{"@id":"https:\/\/influenceassociates.com\/carwow-raises-12-5-million-series-b-led-by-acell\/"},"wordCount":669,"articleSection":["Uncategorised"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/influenceassociates.com\/carwow-raises-12-5-million-series-b-led-by-acell\/","url":"https:\/\/influenceassociates.com\/carwow-raises-12-5-million-series-b-led-by-acell\/","name":"carwow l\u00e8ve 12,5 millions de livres sterling d'investissement - Influence Associates","isPartOf":{"@id":"https:\/\/influenceassociates.com\/#website"},"datePublished":"2016-01-14T16:54:46+00:00","dateModified":"2016-05-06T14:16:32+00:00","author":{"@id":"https:\/\/influenceassociates.com\/#\/schema\/person\/12578eb426032924a60797cb1629f68b"},"breadcrumb":{"@id":"https:\/\/influenceassociates.com\/carwow-raises-12-5-million-series-b-led-by-acell\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/influenceassociates.com\/carwow-raises-12-5-million-series-b-led-by-acell\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/influenceassociates.com\/carwow-raises-12-5-million-series-b-led-by-acell\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/influenceassociates.com\/"},{"@type":"ListItem","position":2,"name":"carwow raises \u00a312.5 Million of investment"}]},{"@type":"WebSite","@id":"https:\/\/influenceassociates.com\/#website","url":"https:\/\/influenceassociates.com\/","name":"Associ\u00e9s d'influence","description":"Communications et relations publiques, strat\u00e9gie de marque et gestion de la r\u00e9putation","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/influenceassociates.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/influenceassociates.com\/#\/schema\/person\/12578eb426032924a60797cb1629f68b","name":"L'\u00e9quipe d'Influence iNews"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/influenceassociates.com\/fr\/wp-json\/wp\/v2\/posts\/980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/influenceassociates.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/influenceassociates.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/influenceassociates.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/influenceassociates.com\/fr\/wp-json\/wp\/v2\/comments?post=980"}],"version-history":[{"count":0,"href":"https:\/\/influenceassociates.com\/fr\/wp-json\/wp\/v2\/posts\/980\/revisions"}],"wp:attachment":[{"href":"https:\/\/influenceassociates.com\/fr\/wp-json\/wp\/v2\/media?parent=980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/influenceassociates.com\/fr\/wp-json\/wp\/v2\/categories?post=980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/influenceassociates.com\/fr\/wp-json\/wp\/v2\/tags?post=980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}